{"id":12106,"date":"2022-05-24T18:48:49","date_gmt":"2022-05-24T18:48:49","guid":{"rendered":"https:\/\/omnius-group.com\/esg\/"},"modified":"2023-03-27T20:33:36","modified_gmt":"2023-03-27T20:33:36","slug":"esg","status":"publish","type":"page","link":"https:\/\/omnius-group.com\/en\/esg\/","title":{"rendered":"ESG"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12106\" class=\"elementor elementor-12106 elementor-8200\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-607a92d elementor-section-full_width elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"607a92d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4326ca5 lakit-col-width-auto-no\" data-id=\"4326ca5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-432045e elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"432045e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpml-elementor-ls\">\n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul role=\"menu\"><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-pt wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\" role=\"none\">\n\t\t\t\t<a href=\"https:\/\/omnius-group.com\/\" class=\"wpml-ls-link\" role=\"menuitem\"  aria-label=\"Switch to PT\" title=\"Switch to PT\" >\n                    <span class=\"wpml-ls-display\">PT<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-current-language wpml-ls-item-legacy-list-horizontal\" role=\"none\">\n\t\t\t\t<a href=\"https:\/\/omnius-group.com\/en\/\" class=\"wpml-ls-link\" role=\"menuitem\" >\n                    <span class=\"wpml-ls-native\" role=\"menuitem\">EN<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\" role=\"none\">\n\t\t\t\t<a href=\"https:\/\/omnius-group.com\/fr\/\" class=\"wpml-ls-link\" role=\"menuitem\"  aria-label=\"Switch to FR\" title=\"Switch to FR\" >\n                    <span class=\"wpml-ls-display\">FR<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-45b1aae elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-bottom elementor-section-boxed elementor-section-height-default e-parent\" data-id=\"45b1aae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-881879b lakit-col-width-auto-no\" data-id=\"881879b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e59ed6b elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"e59ed6b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"preto\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Environment, Social Responsibility and Corporate Governance<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-4ee9233 elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"4ee9233\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ced7460 lakit-col-width-auto-no\" data-id=\"ced7460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-011489c elementor-widget elementor-widget-text-editor\" data-id=\"011489c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>\u201cThere is today a perception in the business sphere that the success of companies and the lasting benefits for their associated agents are not obtained through a focus on maximizing short-term profits, but rather through market-oriented behavior, however coherent and responsible.&#8221;<\/em> <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ff0c4 elementor-widget elementor-widget-text-editor\" data-id=\"53ff0c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Announcement of the Commission of the European Communities, July 2002<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25fa6ef elementor-widget elementor-widget-spacer\" data-id=\"25fa6ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf651cd elementor-widget elementor-widget-text-editor\" data-id=\"bf651cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nowadays, 20 years later, we continue to believe that lasting benefits (comprehensive sustainability \u2013 company, customer, society and environment) are only possible with the involvement and appreciation of people, as they are the ones who create value for companies and customers, and with actions that protect the environment, as good environmental policies and practices can only be applied if people are involved.<\/p>\n<p>These lasting benefits will be the more sustainable the more aligned the parties feel, which is why OMNIUS GROUP is committed to working and applying the best practices, so that this greater objective is achieved.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-9d8da99 elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"9d8da99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4342d8a lakit-col-width-auto-no\" data-id=\"4342d8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ae3915 elementor-widget elementor-widget-heading\" data-id=\"0ae3915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Approach<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-637e3dd elementor-widget elementor-widget-text-editor\" data-id=\"637e3dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The OMNIUS GROUP is simply a promoter that creates processes to motivate\/involve its employees, customers, suppliers and society in general, to develop management practices that, in a continuous way, can develop and improve attitudes and behaviors that aim at social, environmental and economic responsibility.<\/p>\n<p><span style=\"background-color: var(--theme-body-bg-color); color: var(--theme-body-font-color);\">It&#8217;s a simple, all-to-all strategy.<\/span><\/p>\n<p>There are three pillars that are only healthy and sufficiently robust if they are permanently in tune in terms of development in an organization. The collaborators are its drivers.<\/p>\n<p>These values are also fundamental pillars for the sustainability of the group&#8217;s companies.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-109e5f8 lakit-col-width-auto-no\" data-id=\"109e5f8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df1224a elementor-widget elementor-widget-spacer\" data-id=\"df1224a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-c12e744 elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"c12e744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc76170 lakit-col-width-auto-no\" data-id=\"fc76170\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd9d957 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"dd9d957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1130c4 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"a1130c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"418\" height=\"418\" src=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png\" class=\"attachment-large size-large wp-image-11990\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b54ba elementor-widget elementor-widget-text-editor\" data-id=\"d4b54ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Technologies and digitization are fundamental to help make the world more socially, economically and environmentally sustainable. Hence the importance of this vector for OMNIUS.<br \/>Digital technologies are increasingly directed towards people and companies. The aim is to ensure that everyone has the possibility to acquire the necessary skills to participate in the digital society. We are focused on being at the forefront and properly prepared to face the challenges inherent in an evolving, interconnected and sustainable world.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-95c56e6 lakit-col-width-auto-no\" data-id=\"95c56e6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9918ec elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"b9918ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Environment<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3372fab elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"3372fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"418\" height=\"418\" src=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-02.png\" class=\"attachment-large size-large wp-image-11992\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbccd05 elementor-widget elementor-widget-text-editor\" data-id=\"fbccd05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Environmental factors are today a global imperative, placing companies under increasing scrutiny, forcing environmental aspects to be a highly important variable in decision-making. This greater focus means that we are all permanently confronted with new expectations, requiring our firm pro-activity in the search for solutions to reduce our carbon footprint.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-05846b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"05846b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a0afc57 lakit-col-width-auto-no\" data-id=\"a0afc57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bf4f57 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"4bf4f57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Community<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e359c60 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"e359c60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"418\" height=\"418\" src=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-03.png\" class=\"attachment-large size-large wp-image-11994\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e5f41 elementor-widget elementor-widget-text-editor\" data-id=\"43e5f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We get involved and sponsor the promotion of practices and actions that allow the development of communities and society in general. From the inside out, we drive responsibility, integrity and respect for our fellow man. Only from everyone to everyone is it possible to contribute to a better society. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d82c5a elementor-widget elementor-widget-spacer\" data-id=\"9d82c5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c3b54fa lakit-col-width-auto-no\" data-id=\"c3b54fa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-764eea6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"764eea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corporate Governance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df15875 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"df15875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"418\" src=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-04.png\" class=\"attachment-large size-large wp-image-11996\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec31482 elementor-widget elementor-widget-text-editor\" data-id=\"ec31482\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We live and see ourselves as a group, with a very long-term vision of environmental, social and economic sustainability. It is our commitment to the uncompromising defense of the interests of our customers, employees and communities, always supported by transparent and irreproachable structures from a legal, ethical and deontological point of view.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-538f3e9 elementor-widget elementor-widget-spacer\" data-id=\"538f3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-878b2ba elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle e-parent\" data-id=\"878b2ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Video-2022-11-03-at-00.09.39.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a871bb1 lakit-col-width-auto-no\" data-id=\"a871bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-3131002 elementor-section-full_width elementor-section-height-default elementor-section-height-default e-parent\" data-id=\"3131002\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d0e0078 lakit-col-width-auto-no\" data-id=\"5d0e0078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-e6b3a99 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e6b3a99\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-386e2327 lakit-col-width-auto-no\" data-id=\"386e2327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27e0eaa1 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"27e0eaa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1126\" src=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2021\/05\/LOGO_OMNIUS_FOOTER-04.png\" class=\"attachment-full size-full wp-image-12036\" alt=\"\" srcset=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2021\/05\/LOGO_OMNIUS_FOOTER-04.png 2500w, https:\/\/omnius-group.com\/wp-content\/uploads\/2021\/05\/LOGO_OMNIUS_FOOTER-04-1536x692.png 1536w, https:\/\/omnius-group.com\/wp-content\/uploads\/2021\/05\/LOGO_OMNIUS_FOOTER-04-2048x922.png 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1eba87dc lakit-col-width-auto-no\" data-id=\"1eba87dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e67c9e6 elementor-widget elementor-widget-text-editor\" data-id=\"7e67c9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Contacts <br \/><\/strong>Email: <a href=\"mailto:stakeholders@omnius-group.com\">stakeholders@omnius-group.com<\/a><br \/>Phone.: +351 214 028 561<br \/>(Call to Portugal&#8217;s national landline)<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea9c59d elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"ea9c59d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/omnius-group.com\/en\/privacy-policy\/\">Privacy Policy<\/a><br \/><a style=\"background-color: #0f1219;\" href=\"https:\/\/www.livroreclamacoes.pt\/Inicio\/\" target=\"_blank\" rel=\"noopener\">Complaint Book<\/a><\/p>\n<p>OMNIUS GROUP \u00a9 2022. <br \/>All rights reserved.<\/p>\n<p>Developed by <a href=\"https:\/\/boardroom.pt\/\" target=\"_blank\" rel=\"noopener\">BOARDROOM\u2122<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4daefb37 lakit-col-width-auto-no\" data-id=\"4daefb37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64dd2999 elementor-nav-menu--dropdown-none elementor-nav-menu__align-start elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget__width-auto elementor-widget elementor-widget-nav-menu\" data-id=\"64dd2999\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;lakit_floating_fx&quot;:&quot;yes&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-64dd2999\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-12304\"><a href=\"https:\/\/omnius-group.com\/en\/\" class=\"elementor-item\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12305\"><a href=\"https:\/\/omnius-group.com\/en\/about\/\" class=\"elementor-item\">ABOUT<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12306\"><a href=\"https:\/\/omnius-group.com\/en\/esg\/\" class=\"elementor-item\">ESG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12307\"><a href=\"https:\/\/omnius-group.com\/en\/business-area\/\" class=\"elementor-item\">BUSINESS AREA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12308\"><a href=\"https:\/\/omnius-group.com\/en\/people\/\" class=\"elementor-item\">PEOPLE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12309\"><a href=\"https:\/\/omnius-group.com\/en\/stakeholders\/\" class=\"elementor-item\">STAKEHOLDERS<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-64dd2999\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-12304\"><a href=\"https:\/\/omnius-group.com\/en\/\" class=\"elementor-item\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12305\"><a href=\"https:\/\/omnius-group.com\/en\/about\/\" class=\"elementor-item\" tabindex=\"-1\">ABOUT<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12306\"><a href=\"https:\/\/omnius-group.com\/en\/esg\/\" class=\"elementor-item\" tabindex=\"-1\">ESG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12307\"><a href=\"https:\/\/omnius-group.com\/en\/business-area\/\" class=\"elementor-item\" tabindex=\"-1\">BUSINESS AREA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12308\"><a href=\"https:\/\/omnius-group.com\/en\/people\/\" class=\"elementor-item\" tabindex=\"-1\">PEOPLE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12309\"><a href=\"https:\/\/omnius-group.com\/en\/stakeholders\/\" class=\"elementor-item\" tabindex=\"-1\">STAKEHOLDERS<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc7472 elementor-nav-menu--dropdown-none elementor-nav-menu__align-center elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-nav-menu\" data-id=\"4bc7472\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-4bc7472\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-12304\"><a href=\"https:\/\/omnius-group.com\/en\/\" class=\"elementor-item\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12305\"><a href=\"https:\/\/omnius-group.com\/en\/about\/\" class=\"elementor-item\">ABOUT<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12306\"><a href=\"https:\/\/omnius-group.com\/en\/esg\/\" class=\"elementor-item\">ESG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12307\"><a href=\"https:\/\/omnius-group.com\/en\/business-area\/\" class=\"elementor-item\">BUSINESS AREA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12308\"><a href=\"https:\/\/omnius-group.com\/en\/people\/\" class=\"elementor-item\">PEOPLE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12309\"><a href=\"https:\/\/omnius-group.com\/en\/stakeholders\/\" class=\"elementor-item\">STAKEHOLDERS<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-4bc7472\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-12304\"><a href=\"https:\/\/omnius-group.com\/en\/\" class=\"elementor-item\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12305\"><a href=\"https:\/\/omnius-group.com\/en\/about\/\" class=\"elementor-item\" tabindex=\"-1\">ABOUT<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12306\"><a href=\"https:\/\/omnius-group.com\/en\/esg\/\" class=\"elementor-item\" tabindex=\"-1\">ESG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12307\"><a href=\"https:\/\/omnius-group.com\/en\/business-area\/\" class=\"elementor-item\" tabindex=\"-1\">BUSINESS AREA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12308\"><a href=\"https:\/\/omnius-group.com\/en\/people\/\" class=\"elementor-item\" tabindex=\"-1\">PEOPLE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12309\"><a href=\"https:\/\/omnius-group.com\/en\/stakeholders\/\" class=\"elementor-item\" tabindex=\"-1\">STAKEHOLDERS<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d2d0e9 e-grid-align-mobile-center e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"31d2d0e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-2bd4849\" href=\"https:\/\/www.linkedin.com\/company\/trm-technical-resources-management\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794eee0 elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-text-editor\" data-id=\"794eee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/omnius-group.com\/en\/privacy-policy\/\">Privacy Policy<\/a><br \/><a href=\"https:\/\/www.livroreclamacoes.pt\/Inicio\/\" target=\"_blank\" rel=\"noopener\">Complaint Book<\/a><\/p>\n<p>OMNIUS GROUP \u00a9 2022. All rights reserved.<br \/>Developed by <a href=\"https:\/\/boardroom.pt\/\" target=\"_blank\" rel=\"noopener\">BOARDROOM\u2122<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PT EN FR Environment, Social Responsibility and Corporate Governance \u201cThere is today a perception in the business sphere that the success of companies and the lasting benefits for their associated agents are not obtained through a focus [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12106","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/omnius-group.com\/en\/esg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\" \/>\n<meta property=\"og:description\" content=\"PT EN FR Environment, Social Responsibility and Corporate Governance \u201cThere is today a perception in the business sphere that the success of companies and the lasting benefits for their associated agents are not obtained through a focus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/omnius-group.com\/en\/esg\/\" \/>\n<meta property=\"og:site_name\" content=\"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T20:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/\",\"url\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/\",\"name\":\"ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LOGOS-ESG-01.png\",\"datePublished\":\"2022-05-24T18:48:49+00:00\",\"dateModified\":\"2023-03-27T20:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LOGOS-ESG-01.png\",\"contentUrl\":\"https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LOGOS-ESG-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/esg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/\",\"name\":\"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#organization\",\"name\":\"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\",\"url\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/LOGOOMNIUS_PRETO.png\",\"contentUrl\":\"https:\\\/\\\/omnius-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/LOGOOMNIUS_PRETO.png\",\"width\":1032,\"height\":261,\"caption\":\"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services\"},\"image\":{\"@id\":\"https:\\\/\\\/omnius-group.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/omnius-group.com\/en\/esg\/","og_locale":"en_US","og_type":"article","og_title":"ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","og_description":"PT EN FR Environment, Social Responsibility and Corporate Governance \u201cThere is today a perception in the business sphere that the success of companies and the lasting benefits for their associated agents are not obtained through a focus [&hellip;]","og_url":"https:\/\/omnius-group.com\/en\/esg\/","og_site_name":"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","article_modified_time":"2023-03-27T20:33:36+00:00","og_image":[{"url":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/omnius-group.com\/en\/esg\/","url":"https:\/\/omnius-group.com\/en\/esg\/","name":"ESG - OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","isPartOf":{"@id":"https:\/\/omnius-group.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/omnius-group.com\/en\/esg\/#primaryimage"},"image":{"@id":"https:\/\/omnius-group.com\/en\/esg\/#primaryimage"},"thumbnailUrl":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png","datePublished":"2022-05-24T18:48:49+00:00","dateModified":"2023-03-27T20:33:36+00:00","breadcrumb":{"@id":"https:\/\/omnius-group.com\/en\/esg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/omnius-group.com\/en\/esg\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/omnius-group.com\/en\/esg\/#primaryimage","url":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png","contentUrl":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/05\/LOGOS-ESG-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/omnius-group.com\/en\/esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/omnius-group.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"ESG"}]},{"@type":"WebSite","@id":"https:\/\/omnius-group.com\/en\/#website","url":"https:\/\/omnius-group.com\/en\/","name":"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","description":"","publisher":{"@id":"https:\/\/omnius-group.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/omnius-group.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/omnius-group.com\/en\/#organization","name":"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services","url":"https:\/\/omnius-group.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/omnius-group.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/09\/LOGOOMNIUS_PRETO.png","contentUrl":"https:\/\/omnius-group.com\/wp-content\/uploads\/2022\/09\/LOGOOMNIUS_PRETO.png","width":1032,"height":261,"caption":"OMNIUS GROUP, Innovation in Technical &amp; Engineering Services"},"image":{"@id":"https:\/\/omnius-group.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/pages\/12106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/comments?post=12106"}],"version-history":[{"count":12,"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/pages\/12106\/revisions"}],"predecessor-version":[{"id":12741,"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/pages\/12106\/revisions\/12741"}],"wp:attachment":[{"href":"https:\/\/omnius-group.com\/en\/wp-json\/wp\/v2\/media?parent=12106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}